{"id":1351,"date":"2017-04-10T15:38:58","date_gmt":"2017-04-10T21:38:58","guid":{"rendered":"https:\/\/sites.saic.edu\/fvnma2017\/?post_type=artist&#038;p=1351"},"modified":"2017-04-12T09:09:04","modified_gmt":"2017-04-12T15:09:04","slug":"kelsey-velez","status":"publish","type":"artist","link":"https:\/\/sites.saic.edu\/fvnma2017\/artist\/kelsey-velez\/","title":{"rendered":"Kelsey Velez"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":115,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1351","artist","type-artist","status-publish","format-standard","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sites.saic.edu\/fvnma2017\/wp-json\/wp\/v2\/artist\/1351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.saic.edu\/fvnma2017\/wp-json\/wp\/v2\/artist"}],"about":[{"href":"https:\/\/sites.saic.edu\/fvnma2017\/wp-json\/wp\/v2\/types\/artist"}],"author":[{"embeddable":true,"href":"https:\/\/sites.saic.edu\/fvnma2017\/wp-json\/wp\/v2\/users\/115"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.saic.edu\/fvnma2017\/wp-json\/wp\/v2\/comments?post=1351"}],"version-history":[{"count":1,"href":"https:\/\/sites.saic.edu\/fvnma2017\/wp-json\/wp\/v2\/artist\/1351\/revisions"}],"predecessor-version":[{"id":1459,"href":"https:\/\/sites.saic.edu\/fvnma2017\/wp-json\/wp\/v2\/artist\/1351\/revisions\/1459"}],"wp:attachment":[{"href":"https:\/\/sites.saic.edu\/fvnma2017\/wp-json\/wp\/v2\/media?parent=1351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}